{"id":2331,"date":"2021-07-10T05:43:09","date_gmt":"2021-07-10T05:43:09","guid":{"rendered":"https:\/\/vickisatlow.com\/libro\/la-voce-nascosta-delle-pietre\/"},"modified":"2024-11-13T11:28:27","modified_gmt":"2024-11-13T10:28:27","slug":"la-voce-nascosta-delle-pietre","status":"publish","type":"libro","link":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/","title":{"rendered":"The Hidden Voice of Stones"},"template":"","book_tax":[36],"class_list":["post-2331","libro","type-libro","status-publish","hentry","book_tax-fiction-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Hidden Voice of Stones | Vicki Satlow<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Hidden Voice of Stones | Vicki Satlow\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/\" \/>\n<meta property=\"og:site_name\" content=\"Vicki Satlow\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Vicki-Satlow-Literary-Agency\/100060125025546\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T10:28:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vickisatlow.com\/wp-content\/uploads\/2022\/04\/LOGO-VICKI-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/libro\\\/la-voce-nascosta-delle-pietre\\\/\",\"url\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/libro\\\/la-voce-nascosta-delle-pietre\\\/\",\"name\":\"The Hidden Voice of Stones | Vicki Satlow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/#website\"},\"datePublished\":\"2021-07-10T05:43:09+00:00\",\"dateModified\":\"2024-11-13T10:28:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/libro\\\/la-voce-nascosta-delle-pietre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vickisatlow.com\\\/en\\\/libro\\\/la-voce-nascosta-delle-pietre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/libro\\\/la-voce-nascosta-delle-pietre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Hidden Voice of Stones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/\",\"name\":\"Vicki Satlow\",\"description\":\"Literary Agency\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Hidden Voice of Stones | Vicki Satlow","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/","og_locale":"en_US","og_type":"article","og_title":"The Hidden Voice of Stones | Vicki Satlow","og_url":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/","og_site_name":"Vicki Satlow","article_publisher":"https:\/\/www.facebook.com\/people\/Vicki-Satlow-Literary-Agency\/100060125025546\/","article_modified_time":"2024-11-13T10:28:27+00:00","og_image":[{"width":2560,"height":477,"url":"https:\/\/vickisatlow.com\/wp-content\/uploads\/2022\/04\/LOGO-VICKI-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/","url":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/","name":"The Hidden Voice of Stones | Vicki Satlow","isPartOf":{"@id":"https:\/\/vickisatlow.com\/en\/#website"},"datePublished":"2021-07-10T05:43:09+00:00","dateModified":"2024-11-13T10:28:27+00:00","breadcrumb":{"@id":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vickisatlow.com\/en\/libro\/la-voce-nascosta-delle-pietre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vickisatlow.com\/en\/"},{"@type":"ListItem","position":2,"name":"The Hidden Voice of Stones"}]},{"@type":"WebSite","@id":"https:\/\/vickisatlow.com\/en\/#website","url":"https:\/\/vickisatlow.com\/en\/","name":"Vicki Satlow","description":"Literary Agency","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vickisatlow.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/libro\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/libro"}],"about":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/types\/libro"}],"wp:attachment":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"book_tax","embeddable":true,"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/book_tax?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}