{"id":4043,"date":"2023-04-19T14:24:29","date_gmt":"2023-04-19T14:24:29","guid":{"rendered":"https:\/\/vickisatlow.com\/autore\/valeria-di-napoli\/"},"modified":"2024-01-22T07:44:37","modified_gmt":"2024-01-22T07:44:37","slug":"valeria-di-napoli","status":"publish","type":"autore","link":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/","title":{"rendered":"Pulsatilla"},"template":"","class_list":["post-4043","autore","type-autore","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pulsatilla | Vicki Satlow<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pulsatilla | Vicki Satlow\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Vicki Satlow\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Vicki-Satlow-Literary-Agency\/100060125025546\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T07:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vickisatlow.com\/wp-content\/uploads\/2022\/04\/LOGO-VICKI-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/autore\\\/valeria-di-napoli\\\/\",\"url\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/autore\\\/valeria-di-napoli\\\/\",\"name\":\"Pulsatilla | Vicki Satlow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/#website\"},\"datePublished\":\"2023-04-19T14:24:29+00:00\",\"dateModified\":\"2024-01-22T07:44:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/autore\\\/valeria-di-napoli\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vickisatlow.com\\\/en\\\/autore\\\/valeria-di-napoli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/autore\\\/valeria-di-napoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pulsatilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/\",\"name\":\"Vicki Satlow\",\"description\":\"Literary Agency\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vickisatlow.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pulsatilla | Vicki Satlow","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/","og_locale":"en_US","og_type":"article","og_title":"Pulsatilla | Vicki Satlow","og_url":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/","og_site_name":"Vicki Satlow","article_publisher":"https:\/\/www.facebook.com\/people\/Vicki-Satlow-Literary-Agency\/100060125025546\/","article_modified_time":"2024-01-22T07:44:37+00:00","og_image":[{"width":2560,"height":477,"url":"https:\/\/vickisatlow.com\/wp-content\/uploads\/2022\/04\/LOGO-VICKI-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/","url":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/","name":"Pulsatilla | Vicki Satlow","isPartOf":{"@id":"https:\/\/vickisatlow.com\/en\/#website"},"datePublished":"2023-04-19T14:24:29+00:00","dateModified":"2024-01-22T07:44:37+00:00","breadcrumb":{"@id":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vickisatlow.com\/en\/autore\/valeria-di-napoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vickisatlow.com\/en\/"},{"@type":"ListItem","position":2,"name":"Pulsatilla"}]},{"@type":"WebSite","@id":"https:\/\/vickisatlow.com\/en\/#website","url":"https:\/\/vickisatlow.com\/en\/","name":"Vicki Satlow","description":"Literary Agency","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vickisatlow.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/autore\/4043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/autore"}],"about":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/types\/autore"}],"wp:attachment":[{"href":"https:\/\/vickisatlow.com\/en\/wp-json\/wp\/v2\/media?parent=4043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}